{"id":28441,"date":"2016-05-01T09:03:58","date_gmt":"2016-05-01T08:03:58","guid":{"rendered":"http:\/\/www.libraria-occitana.org\/all-products\/e-lo-ser-tombet-un-cop-de-mai-et-le-soir-tomba-une-fois-de-plus?lang=en"},"modified":"2026-04-29T11:01:55","modified_gmt":"2026-04-29T09:01:55","slug":"e-lo-ser-tombet-un-cop-de-mai-et-le-soir-tomba-une-fois-de-plus","status":"publish","type":"product","link":"https:\/\/www.libraria-occitana.org\/en\/product\/e-lo-ser-tombet-un-cop-de-mai-et-le-soir-tomba-une-fois-de-plus\/","title":{"rendered":"E lo ser tombet, un c\u00f2p de mai &#8211; Et le soir tomba, une fois de plus"},"content":{"rendered":"<p><strong>[oc]<\/strong><br \/>\nEn occitan emb la revirada en franc\u00e9s sus la paja a costat.<\/p>\n<p>Dempuei <em>Lo dever del vaure<\/em>, paregut a &#8216;quelas edicions e que li valguet lo premi Jaufre Rudel, Joan-Peire Lacomba nos a balhat de legir bona \u00f2bra en lenga n\u00f2stra. (E parle pas de son \u00f2bra francimanda que l-i desb\u00f2tja maitot bon fiau.) De las novelas, paregudas jos lo titol <em>Daus vistons dins la nuech<\/em>, de las reviradas (la de <em>The pearl<\/em> de John Steinbeck, la de <em>Du loup et de la biche<\/em> de Luc de Goustine) e uei &#8216;queu noveu libre de sa poesia.<br \/>\nQue d&#8217;en prumier, coma d&#8217;evidencia, coma de neciera, e d&#8217;alhors se fagues-t-eu prosador, Joan-Peire Lacomba es poeta.<br \/>\nE tornaretz trobar &#8216;qu\u00ed \u00e7\u00f2 qu&#8217;aviatz aimat dins <em>Lo dever del vaure<\/em>, &#8216;quilhs poemas, lo mai sovent de quauques mots, clafits de vita, que daus uns c\u00f2ps diriensatz proverbis, que tots fan imatge. E dins quau lenga ! &#8211; saba, sabor, saber &#8211; siguessa en lemosin o en auvernhat.<\/p>\n<p><strong>[fr]<\/strong><br \/>\nEn occitan avec traduction fran\u00e7aise en regard.<\/p>\n<p>Depuis <em>Lo dever del vaure<\/em>, paru \u00e0 ces \u00e9ditions et qui lui valut le prix Jaufre Rudel, Jean-Pierre Lacombe nous a donn\u00e9 \u00e0 lire bonne \u0153uvre dans notre langue. ( Et je ne parle pas de son \u0153uvre en fran\u00e7ais qu&#8217;il d\u00e9vide aussi de bon fil.) Des nouvelles, parues sous le titre <em>Daus vistons dins la nuech<\/em>, des traductions (celle de <em>The pearl<\/em> de John Steinbeck, celle de <em>Du loup et de la biche<\/em> de Luc de Goustine) et aujourd&#8217;hui ce nouveau livre de sa po\u00e9sie.<br \/>\nCar avant tout, comme d&#8217;\u00e9vidence, comme de n\u00e9cessit\u00e9, et d&#8217;ailleurs se f\u00eet-il prosateur, Jean-Pierre Lacombe est po\u00e8te.<br \/>\nEt l&#8217;on retrouvera l\u00e0 ce qu&#8217;on a aim\u00e9 dans <em>Lo dever del vaure<\/em>, ces po\u00e8mes, le plus souvent de quelques mots, regorgeant de vie, que parfois l&#8217;on dirait proverbes, qui tous font image. Et dans quelle langue ! &#8211; s\u00e8ve, saveur, savoir &#8211; que ce soit en limousin ou en auvergnat.<\/p>\n<blockquote>\n<p>La nuech<br \/>\nes mas un jorn de lum negre<br \/>\nde lagremas mai priondas.<\/p>\n<p>La vergonha<br \/>\nlos fasi\u00e1 s&#8217;aturar<br \/>\nd-a l&#8217;eime de las b\u00e8stias f\u00e8ras.<\/p>\n<p>Lo vent ne&#8217;n veni\u00e1<br \/>\nde la fi\u00e8ira<br \/>\nonte viron las belas sasons.<\/p>\n<\/blockquote>\n<p><em>La nuit<br \/>\nn&#8217;est qu&#8217;un jour de lumi\u00e8re noire<br \/>\nde larmes plus profondes.<br \/>\nLa honte<br \/>\nles faisait s&#8217;adosser<br \/>\n\u00e0 l&#8217;esprit des b\u00eates sauvages.<br \/>\nLe vent en venait<br \/>\nde la foire<br \/>\no\u00f9 tournent les grandes saisons.<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>[oc] En occitan emb la revirada en franc\u00e9s sus la paja a costat. Dempuei Lo dever del vaure, paregut a &#8216;quelas edicions e que li valguet lo premi Jaufre Rudel, Joan-Peire Lacomba nos a balhat de legir bona \u00f2bra en lenga n\u00f2stra. (E parle pas de son \u00f2bra francimanda que l-i desb\u00f2tja maitot bon fiau.) [&hellip;]<\/p>\n","protected":false},"featured_media":28439,"template":"","meta":{"_acf_changed":false,"_genesis_hide_title":false,"_genesis_hide_breadcrumbs":false,"_genesis_hide_singular_image":false,"_genesis_hide_footer_widgets":false,"_genesis_custom_body_class":"","_genesis_custom_post_class":"","_genesis_layout":""},"product_brand":[],"product_cat":[7132,7174,7180],"product_tag":[],"class_list":{"0":"post-28441","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-books","7":"product_cat-literature-en","8":"product_cat-poetry-en","9":"pa_auteur-lacombe-jean-pierre-fr-en","10":"pa_editeur-lo-chamin-de-sent-jaume-en","11":"pa_langue-occitan-lemosin-en","12":"pa_langue-occitan-francais-en","13":"entry","15":"first","16":"instock","17":"shipping-taxable","18":"purchasable","19":"product-type-simple"},"acf":[],"_links":{"self":[{"href":"https:\/\/www.libraria-occitana.org\/en\/wp-json\/wp\/v2\/product\/28441","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.libraria-occitana.org\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.libraria-occitana.org\/en\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.libraria-occitana.org\/en\/wp-json\/wp\/v2\/media\/28439"}],"wp:attachment":[{"href":"https:\/\/www.libraria-occitana.org\/en\/wp-json\/wp\/v2\/media?parent=28441"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/www.libraria-occitana.org\/en\/wp-json\/wp\/v2\/product_brand?post=28441"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.libraria-occitana.org\/en\/wp-json\/wp\/v2\/product_cat?post=28441"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.libraria-occitana.org\/en\/wp-json\/wp\/v2\/product_tag?post=28441"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}